{"id":7632,"date":"2024-03-11T10:37:06","date_gmt":"2024-03-11T09:37:06","guid":{"rendered":"http:\/\/hasler-gp.com\/?post_type=expertise&#038;p=7632"},"modified":"2025-08-12T14:40:29","modified_gmt":"2025-08-12T12:40:29","slug":"il-etait-une-fois-les-melangeurs-et-agitateurs-lumpp","status":"publish","type":"expertise","link":"https:\/\/hasler-gp.com\/fr\/expertise\/il-etait-une-fois-les-melangeurs-et-agitateurs-lumpp\/","title":{"rendered":"IL ETAIT UNE FOIS, LES MELANGEURS ET AGITATEURS LUMPP"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">L&rsquo;expertise en mati\u00e8re de m\u00e9lange industriel depuis 1875<\/h2>\n\n\n\n<p>Fond\u00e9 en 1875, LUMPP est un acteur majeur dans la conception et la construction de solutions d&rsquo;agitation. Elle n&rsquo;a cess\u00e9 d&rsquo;\u00e9tendre son expertise dans l&rsquo;industrie chimique et s&rsquo;est diversifi\u00e9e dans une myriade d&rsquo;autres domaines. Gr\u00e2ce \u00e0 la large gamme de m\u00e9langeurs LUMPP et \u00e0 leur efficacit\u00e9 prouv\u00e9e, il est toujours possible de trouver le syst\u00e8me de m\u00e9lange optimal pour vos besoins. Quelle que soit leur taille ou leur complexit\u00e9, les avantages pour les utilisateurs et la fiabilit\u00e9 de nos syst\u00e8mes d&rsquo;agitation sont toujours au premier plan.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"576\" src=\"http:\/\/hasler-gp.com\/wp-content\/uploads\/2024\/03\/melangeurs-agitateurs-industriels-1024x576.png\" alt=\"Melangeurs et agitateurs industriels LUMPP\" class=\"wp-image-7633\" srcset=\"https:\/\/hasler-gp.com\/wp-content\/uploads\/2024\/03\/melangeurs-agitateurs-industriels-1024x576.png 1024w, https:\/\/hasler-gp.com\/wp-content\/uploads\/2024\/03\/melangeurs-agitateurs-industriels-300x169.png 300w, https:\/\/hasler-gp.com\/wp-content\/uploads\/2024\/03\/melangeurs-agitateurs-industriels-768x432.png 768w, https:\/\/hasler-gp.com\/wp-content\/uploads\/2024\/03\/melangeurs-agitateurs-industriels-1536x864.png 1536w, https:\/\/hasler-gp.com\/wp-content\/uploads\/2024\/03\/melangeurs-agitateurs-industriels-400x225.png 400w, https:\/\/hasler-gp.com\/wp-content\/uploads\/2024\/03\/melangeurs-agitateurs-industriels-1000x563.png 1000w, https:\/\/hasler-gp.com\/wp-content\/uploads\/2024\/03\/melangeurs-agitateurs-industriels.png 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Gamme de produits LUMPP<\/h2>\n\n\n\n<p>LUMPP fournit des <strong>solutions d&rsquo;agitation<\/strong> de premier ordre adapt\u00e9es aux besoins des industries de traitement en continu gr\u00e2ce \u00e0 une gamme compl\u00e8te de <strong>m\u00e9langeurs et d&rsquo;agitateurs industriels<\/strong>, y compris des <strong>agitateurs \u00e0 double mouvement<\/strong>, des<strong> m\u00e9langeurs \u00e0 haute viscosit\u00e9<\/strong>, des<strong> agitateurs horizontaux<\/strong> et <strong>verticaux <\/strong>et des <strong>m\u00e9langeurs pour charges lourdes<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">L&rsquo;histoire&nbsp;<\/h2>\n\n\n\n<ul>\n<li>1875 : Oscar LUMPP fonde la soci\u00e9t\u00e9 LUMPP et acquiert un petit commerce de machines \u00e0 vapeur et d&rsquo;\u00e9quipements pour l&rsquo;industrie du gaz.<\/li>\n\n\n\n<li>1912 : LUMPP con\u00e7oit de nouvelles solutions de m\u00e9lange industriel pour l&rsquo;homog\u00e9n\u00e9isation des liquides.<\/li>\n\n\n\n<li>1918 : l&rsquo;entreprise se d\u00e9veloppe dans le domaine des machines pour le tannage et la teinture, puis s&rsquo;oriente vers la fabrication de machines pour l&rsquo;industrie chimique.<\/li>\n\n\n\n<li>2013 : La soci\u00e9t\u00e9 LUMPP int\u00e8gre le groupe HASLER.<\/li>\n\n\n\n<li>Aujourd&rsquo;hui : la ligne de produits LUMPP est sp\u00e9cialis\u00e9e dans la fourniture d&rsquo;une large gamme de m\u00e9langeurs et d&rsquo;agitateurs industriels, y compris les agitateurs \u00e0 haute viscosit\u00e9 et \u00e0 double mouvement et les racleurs industriels.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"576\" src=\"http:\/\/hasler-gp.com\/wp-content\/uploads\/2024\/03\/lumpp_melangeurs_et_agitateurs_expertise_en_melange_industriel_depuis_1875-1024x576.jpg\" alt=\"M\u00e9langeurs et agitateurs LUMPP, expert depuis 1875\" class=\"wp-image-7635\" srcset=\"https:\/\/hasler-gp.com\/wp-content\/uploads\/2024\/03\/lumpp_melangeurs_et_agitateurs_expertise_en_melange_industriel_depuis_1875-1024x576.jpg 1024w, https:\/\/hasler-gp.com\/wp-content\/uploads\/2024\/03\/lumpp_melangeurs_et_agitateurs_expertise_en_melange_industriel_depuis_1875-300x169.jpg 300w, https:\/\/hasler-gp.com\/wp-content\/uploads\/2024\/03\/lumpp_melangeurs_et_agitateurs_expertise_en_melange_industriel_depuis_1875-768x432.jpg 768w, https:\/\/hasler-gp.com\/wp-content\/uploads\/2024\/03\/lumpp_melangeurs_et_agitateurs_expertise_en_melange_industriel_depuis_1875-1536x864.jpg 1536w, https:\/\/hasler-gp.com\/wp-content\/uploads\/2024\/03\/lumpp_melangeurs_et_agitateurs_expertise_en_melange_industriel_depuis_1875-400x225.jpg 400w, https:\/\/hasler-gp.com\/wp-content\/uploads\/2024\/03\/lumpp_melangeurs_et_agitateurs_expertise_en_melange_industriel_depuis_1875-1000x563.jpg 1000w, https:\/\/hasler-gp.com\/wp-content\/uploads\/2024\/03\/lumpp_melangeurs_et_agitateurs_expertise_en_melange_industriel_depuis_1875.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Expertise&nbsp;<\/h2>\n\n\n\n<p>L&rsquo;expertise de LUMPP repose sur trois grands piliers :<\/p>\n\n\n\n<ul start=\"1\">\n<li><strong>Performance <\/strong>: Les m\u00e9langeurs, agitateurs et racleurs industriels LUMPP sont con\u00e7us pour r\u00e9pondre aux normes de performance les plus \u00e9lev\u00e9es de l&rsquo;industrie. Son \u00e9quipe d&rsquo;ing\u00e9nieurs exp\u00e9riment\u00e9s utilise les technologies les plus r\u00e9centes pour concevoir et fabriquer ses m\u00e9langeurs. Les m\u00e9langeurs LUMPP sont \u00e9galement soumis \u00e0 des tests rigoureux pour s&rsquo;assurer qu&rsquo;ils r\u00e9pondent aux sp\u00e9cifications \u00e9lev\u00e9es requises.<\/li>\n<\/ul>\n\n\n\n<ul start=\"2\">\n<li><strong>Qualit\u00e9 <\/strong>: Les m\u00e9langeurs LUMPP sont fabriqu\u00e9s en acier inoxydable et autres mat\u00e9riaux r\u00e9sistants \u00e0 la corrosion, ainsi que des composants usin\u00e9s avec pr\u00e9cision pour garantir pr\u00e9cision et fiabilit\u00e9. LUMPP a mis en place un processus strict de contr\u00f4le de la qualit\u00e9 pour s&rsquo;assurer que ses produits r\u00e9pondent aux normes les plus strictes.<\/li>\n<\/ul>\n\n\n\n<ul start=\"3\">\n<li><strong>Fiabilit\u00e9 <\/strong>: Les agitateurs, m\u00e9langeurs et racleurs industriels LUMPP sont con\u00e7us pour \u00eatre fiables et durables. Ils utilisent une vari\u00e9t\u00e9 de caract\u00e9ristiques de conception pour am\u00e9liorer la fiabilit\u00e9. Par exemple, les agitateurs LUMPP sont dot\u00e9s d&rsquo;un syst\u00e8me de roulement \u00e9tanche qui prot\u00e8ge les roulements des contaminants et prolonge leur dur\u00e9e de vie.<\/li>\n<\/ul>\n\n\n\n<p>Les m\u00e9langeurs, agitateurs et racleurs LUMPP couvrent un large \u00e9ventail d&rsquo;activit\u00e9s industrielles dans le monde entier : industrie chimique et p\u00e9trochimique, d\u00e9sulfuration des gaz de combustion, industrie du papier, industrie phosphorique, hydrom\u00e9tallurgie.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-3 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"724\" height=\"1024\" src=\"http:\/\/hasler-gp.com\/wp-content\/uploads\/2024\/03\/solutions-agitation-LUMPP-724x1024.png\" alt=\"Solutions d'agitation LUMPP\" class=\"wp-image-7637\" srcset=\"https:\/\/hasler-gp.com\/wp-content\/uploads\/2024\/03\/solutions-agitation-LUMPP-724x1024.png 724w, https:\/\/hasler-gp.com\/wp-content\/uploads\/2024\/03\/solutions-agitation-LUMPP-212x300.png 212w, https:\/\/hasler-gp.com\/wp-content\/uploads\/2024\/03\/solutions-agitation-LUMPP-768x1086.png 768w, https:\/\/hasler-gp.com\/wp-content\/uploads\/2024\/03\/solutions-agitation-LUMPP-1086x1536.png 1086w, https:\/\/hasler-gp.com\/wp-content\/uploads\/2024\/03\/solutions-agitation-LUMPP-1448x2048.png 1448w, https:\/\/hasler-gp.com\/wp-content\/uploads\/2024\/03\/solutions-agitation-LUMPP-283x400.png 283w, https:\/\/hasler-gp.com\/wp-content\/uploads\/2024\/03\/solutions-agitation-LUMPP-707x1000.png 707w, https:\/\/hasler-gp.com\/wp-content\/uploads\/2024\/03\/solutions-agitation-LUMPP.png 1645w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"724\" height=\"1024\" src=\"http:\/\/hasler-gp.com\/wp-content\/uploads\/2024\/03\/gamme-agitateurs-melangeurs-LUMPP-724x1024.png\" alt=\"Gamme d'agitateurs et m\u00e9langeurs LUMPP\" class=\"wp-image-7639\" srcset=\"https:\/\/hasler-gp.com\/wp-content\/uploads\/2024\/03\/gamme-agitateurs-melangeurs-LUMPP-724x1024.png 724w, https:\/\/hasler-gp.com\/wp-content\/uploads\/2024\/03\/gamme-agitateurs-melangeurs-LUMPP-212x300.png 212w, https:\/\/hasler-gp.com\/wp-content\/uploads\/2024\/03\/gamme-agitateurs-melangeurs-LUMPP-768x1086.png 768w, https:\/\/hasler-gp.com\/wp-content\/uploads\/2024\/03\/gamme-agitateurs-melangeurs-LUMPP-1086x1536.png 1086w, https:\/\/hasler-gp.com\/wp-content\/uploads\/2024\/03\/gamme-agitateurs-melangeurs-LUMPP-1448x2048.png 1448w, https:\/\/hasler-gp.com\/wp-content\/uploads\/2024\/03\/gamme-agitateurs-melangeurs-LUMPP-283x400.png 283w, https:\/\/hasler-gp.com\/wp-content\/uploads\/2024\/03\/gamme-agitateurs-melangeurs-LUMPP-707x1000.png 707w, https:\/\/hasler-gp.com\/wp-content\/uploads\/2024\/03\/gamme-agitateurs-melangeurs-LUMPP.png 1645w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p><strong><a href=\"\/fr\/le-groupe\/\">D\u00e9couvrez HASLER Group<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;expertise en mati\u00e8re de m\u00e9lange industriel depuis 1875 Fond\u00e9 en 1875, LUMPP est un acteur majeur dans la conception et la construction de solutions d&rsquo;agitation. Elle n&rsquo;a cess\u00e9 d&rsquo;\u00e9tendre son expertise dans l&rsquo;industrie chimique et s&rsquo;est diversifi\u00e9e dans une myriade d&rsquo;autres domaines. Gr\u00e2ce \u00e0 la large gamme de m\u00e9langeurs LUMPP et \u00e0 leur efficacit\u00e9 prouv\u00e9e, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":7643,"comment_status":"open","ping_status":"closed","template":"","cat-expertise":[67],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>IL ETAIT UNE FOIS, LES MELANGEURS ET AGITATEURS LUMPP - HASLER Group<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez l&#039;expertise en m\u00e9lange industriel de LUMPP depuis 1875, avec une gamme vari\u00e9e de m\u00e9langeurs et agitateurs de qualit\u00e9 sup\u00e9rieure\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hasler-gp.com\/fr\/expertise\/il-etait-une-fois-les-melangeurs-et-agitateurs-lumpp\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IL ETAIT UNE FOIS, LES MELANGEURS ET AGITATEURS LUMPP - HASLER Group\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez l&#039;expertise en m\u00e9lange industriel de LUMPP depuis 1875, avec une gamme vari\u00e9e de m\u00e9langeurs et agitateurs de qualit\u00e9 sup\u00e9rieure\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hasler-gp.com\/fr\/expertise\/il-etait-une-fois-les-melangeurs-et-agitateurs-lumpp\/\" \/>\n<meta property=\"og:site_name\" content=\"HASLER Group\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-12T12:40:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hasler-gp.com\/wp-content\/uploads\/2024\/03\/LUMPP-acteur-historique-agitateurs-melangeurs-industriels-e1711037354842.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1062\" \/>\n\t<meta property=\"og:image:height\" content=\"899\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hasler-gp.com\/fr\/expertise\/il-etait-une-fois-les-melangeurs-et-agitateurs-lumpp\/\",\"url\":\"https:\/\/hasler-gp.com\/fr\/expertise\/il-etait-une-fois-les-melangeurs-et-agitateurs-lumpp\/\",\"name\":\"IL ETAIT UNE FOIS, LES MELANGEURS ET AGITATEURS LUMPP - HASLER Group\",\"isPartOf\":{\"@id\":\"https:\/\/hasler-gp.com\/fr\/#website\"},\"datePublished\":\"2024-03-11T09:37:06+00:00\",\"dateModified\":\"2025-08-12T12:40:29+00:00\",\"description\":\"D\u00e9couvrez l'expertise en m\u00e9lange industriel de LUMPP depuis 1875, avec une gamme vari\u00e9e de m\u00e9langeurs et agitateurs de qualit\u00e9 sup\u00e9rieure\",\"breadcrumb\":{\"@id\":\"https:\/\/hasler-gp.com\/fr\/expertise\/il-etait-une-fois-les-melangeurs-et-agitateurs-lumpp\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hasler-gp.com\/fr\/expertise\/il-etait-une-fois-les-melangeurs-et-agitateurs-lumpp\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hasler-gp.com\/fr\/expertise\/il-etait-une-fois-les-melangeurs-et-agitateurs-lumpp\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/hasler-gp.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Expertise\",\"item\":\"https:\/\/hasler-gp.com\/fr\/expertise\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"IL ETAIT UNE FOIS, LES MELANGEURS ET AGITATEURS LUMPP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hasler-gp.com\/fr\/#website\",\"url\":\"https:\/\/hasler-gp.com\/fr\/\",\"name\":\"HASLER Group\",\"description\":\"Un site utilisant WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hasler-gp.com\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IL ETAIT UNE FOIS, LES MELANGEURS ET AGITATEURS LUMPP - HASLER Group","description":"D\u00e9couvrez l'expertise en m\u00e9lange industriel de LUMPP depuis 1875, avec une gamme vari\u00e9e de m\u00e9langeurs et agitateurs de qualit\u00e9 sup\u00e9rieure","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hasler-gp.com\/fr\/expertise\/il-etait-une-fois-les-melangeurs-et-agitateurs-lumpp\/","og_locale":"fr_FR","og_type":"article","og_title":"IL ETAIT UNE FOIS, LES MELANGEURS ET AGITATEURS LUMPP - HASLER Group","og_description":"D\u00e9couvrez l'expertise en m\u00e9lange industriel de LUMPP depuis 1875, avec une gamme vari\u00e9e de m\u00e9langeurs et agitateurs de qualit\u00e9 sup\u00e9rieure","og_url":"https:\/\/hasler-gp.com\/fr\/expertise\/il-etait-une-fois-les-melangeurs-et-agitateurs-lumpp\/","og_site_name":"HASLER Group","article_modified_time":"2025-08-12T12:40:29+00:00","og_image":[{"width":1062,"height":899,"url":"https:\/\/hasler-gp.com\/wp-content\/uploads\/2024\/03\/LUMPP-acteur-historique-agitateurs-melangeurs-industriels-e1711037354842.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hasler-gp.com\/fr\/expertise\/il-etait-une-fois-les-melangeurs-et-agitateurs-lumpp\/","url":"https:\/\/hasler-gp.com\/fr\/expertise\/il-etait-une-fois-les-melangeurs-et-agitateurs-lumpp\/","name":"IL ETAIT UNE FOIS, LES MELANGEURS ET AGITATEURS LUMPP - HASLER Group","isPartOf":{"@id":"https:\/\/hasler-gp.com\/fr\/#website"},"datePublished":"2024-03-11T09:37:06+00:00","dateModified":"2025-08-12T12:40:29+00:00","description":"D\u00e9couvrez l'expertise en m\u00e9lange industriel de LUMPP depuis 1875, avec une gamme vari\u00e9e de m\u00e9langeurs et agitateurs de qualit\u00e9 sup\u00e9rieure","breadcrumb":{"@id":"https:\/\/hasler-gp.com\/fr\/expertise\/il-etait-une-fois-les-melangeurs-et-agitateurs-lumpp\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hasler-gp.com\/fr\/expertise\/il-etait-une-fois-les-melangeurs-et-agitateurs-lumpp\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hasler-gp.com\/fr\/expertise\/il-etait-une-fois-les-melangeurs-et-agitateurs-lumpp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/hasler-gp.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Expertise","item":"https:\/\/hasler-gp.com\/fr\/expertise\/"},{"@type":"ListItem","position":3,"name":"IL ETAIT UNE FOIS, LES MELANGEURS ET AGITATEURS LUMPP"}]},{"@type":"WebSite","@id":"https:\/\/hasler-gp.com\/fr\/#website","url":"https:\/\/hasler-gp.com\/fr\/","name":"HASLER Group","description":"Un site utilisant WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hasler-gp.com\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/hasler-gp.com\/fr\/wp-json\/wp\/v2\/expertise\/7632"}],"collection":[{"href":"https:\/\/hasler-gp.com\/fr\/wp-json\/wp\/v2\/expertise"}],"about":[{"href":"https:\/\/hasler-gp.com\/fr\/wp-json\/wp\/v2\/types\/expertise"}],"author":[{"embeddable":true,"href":"https:\/\/hasler-gp.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/hasler-gp.com\/fr\/wp-json\/wp\/v2\/comments?post=7632"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hasler-gp.com\/fr\/wp-json\/wp\/v2\/media\/7643"}],"wp:attachment":[{"href":"https:\/\/hasler-gp.com\/fr\/wp-json\/wp\/v2\/media?parent=7632"}],"wp:term":[{"taxonomy":"cat-expertise","embeddable":true,"href":"https:\/\/hasler-gp.com\/fr\/wp-json\/wp\/v2\/cat-expertise?post=7632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}